{"id":6009,"date":"2020-12-11T00:37:41","date_gmt":"2020-12-11T03:37:41","guid":{"rendered":"https:\/\/www.rrservicene.com.br\/loja\/?post_type=product&#038;p=6009"},"modified":"2020-12-11T00:37:41","modified_gmt":"2020-12-11T03:37:41","slug":"compressor-de-ar-de-parafuso-scroll-scr-4005-ad-ar-direto","status":"publish","type":"product","link":"http:\/\/rrservicene.com.br\/loja\/product\/compressor-de-ar-de-parafuso-scroll-scr-4005-ad-ar-direto\/","title":{"rendered":"COMPRESSOR DE AR DE PARAFUSO SCROLL SCR 4005 AD &#8211; AR DIRETO"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<th colspan=\"2\">DETALHES ADICIONAIS<\/th>\n<\/tr>\n<tr>\n<td width=\"50%\">Pot\u00eancia do motor<\/td>\n<td width=\"50%\">5 hp<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">Press\u00e3o de trabalho (bar)<\/td>\n<td width=\"50%\">6-8<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">Vaz\u00e3o (pcm)<\/td>\n<td width=\"50%\">14,5<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">Conex\u00e3o de sa\u00edda<\/td>\n<td width=\"50%\">R 1\/2&#8243;<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">Dimens\u00e3o C x L x A (mm)<\/td>\n<td width=\"50%\">1100 x 710 x 475<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">Peso L\u00edquido (Kg)<\/td>\n<td width=\"50%\">194<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Os\u00a0<strong>compressores com tecnologia de compress\u00e3o Scroll da Schulz<\/strong>\u00a0possuem como principal caracter\u00edstica a gera\u00e7\u00e3o de ar comprimido\u00a0<strong>isento de \u00f3leo<\/strong>\u00a0para aplica\u00e7\u00f5es cr\u00edticas, como nos segmentos de alimentos, bebidas, semicondutores, cosm\u00e9ticos ou ainda na \u00e1rea da sa\u00fade como farmac\u00eauticas e m\u00e9dico\/hospitalar.<\/p>\n<p>Os modelos\u00a0<strong>Scroll<\/strong>\u00a0integram ainda secador de ar e reservat\u00f3rio, que permitem gerar, tratar e armazenar ar comprimido de alta qualidade livre de condensado com menor espa\u00e7o ocupado e menos gastos de instala\u00e7\u00f5es. Escolha a melhor op\u00e7\u00e3o para a sua empresa.<\/p>\n","protected":false},"featured_media":6010,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/product\/6009"}],"collection":[{"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/comments?post=6009"}],"version-history":[{"count":1,"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/product\/6009\/revisions"}],"predecessor-version":[{"id":6011,"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/product\/6009\/revisions\/6011"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/media\/6010"}],"wp:attachment":[{"href":"http:\/\/rrservicene.com.br\/loja\/wp-json\/wp\/v2\/media?parent=6009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}